{"id":14749,"date":"2023-01-23T08:00:00","date_gmt":"2023-01-23T11:00:00","guid":{"rendered":"https:\/\/latinoamerica21.com\/?p=14749"},"modified":"2023-11-09T17:11:52","modified_gmt":"2023-11-09T20:11:52","slug":"los-jueces-tambien-hacen-politica","status":"publish","type":"post","link":"https:\/\/latinoamerica21.com\/es\/los-jueces-tambien-hacen-politica\/","title":{"rendered":"Los jueces tambi\u00e9n hacen pol\u00edtica"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El 21 de diciembre de 2022, el acad\u00e9mico de la UNAM, Guillermo Sheridan, demostr\u00f3 que la actual ministra de la Suprema Corte de Justicia de la Naci\u00f3n (SCJN), de M\u00e9xico,<a href=\"https:\/\/elpais.com\/mexico\/2023-01-12\/la-unam-concluye-que-la-tesis-de-1987-de-la-ministra-yasmin-esquivel-es-un-plagio.html\" target=\"_blank\" rel=\"noreferrer noopener\"> Yasm\u00edn Esquivel, hab\u00eda plagiado totalmente una tesis de licenciatura<\/a> con la que obtuvo el t\u00edtulo de abogada en 1987. En los d\u00edas que siguieron, Esquivel lo neg\u00f3 de manera sistem\u00e1tica, pero en el repositorio digital de la UNAM, que contiene todas las tesis, se pod\u00eda corroborar el plagio.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Finalmente, el 11 de enero la universidad confirm\u00f3 que la ministra obtuvo su grado de forma fraudulenta y en colusi\u00f3n con su asesora de tesis. Sin embargo, la misma universidad se\u00f1al\u00f3 que la Secretar\u00eda de Educaci\u00f3n P\u00fablica, autoridad del Estado encargada de reconocer los grados acad\u00e9micos, es el organismo que puede retirar el t\u00edtulo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En casi todo el mundo el poder judicial es monop\u00f3lico disciplinar; solo los que tienen un t\u00edtulo en derecho pueden acceder a la carrera judicial. Un t\u00edtulo acad\u00e9mico demuestra una formaci\u00f3n y habilita a una persona para ejercer una profesi\u00f3n, pero, si se obtiene de manera fraudulenta, toda esa carrera habr\u00e1 sido una simulaci\u00f3n.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por ello, este no es un caso m\u00e1s de plagio acad\u00e9mico. Se trata de una magistrada de la corte suprema, uno de los cargos m\u00e1s importantes del Estado, y su legitimidad se basa tanto en el proceso formal para designarla como en su carrera y reputaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esquivel, sin embargo, es esposa de Jos\u00e9 Mar\u00eda Riob\u00f3o, uno de los principales contratistas del presidente de M\u00e9xico, Andr\u00e9s Manuel L\u00f3pez Obrador, y muy cercano desde que gobern\u00f3 la Ciudad de M\u00e9xico. Esta condici\u00f3n, y no tanto su carrera, le permiti\u00f3 a Esquivel el que el Ejecutivo la propusiera para ocupar el cargo de ministra de la SCJN. As\u00ed, su caso pone bajo la lupa la legitimidad de los jueces, el peso de sus decisiones, el importante papel pol\u00edtico de las instituciones judiciales como garantes del Estado de derecho, pero tambi\u00e9n los peligros de la politizaci\u00f3n de la justicia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Los jueces no son la boca de la ley<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los jueces hacen pol\u00edtica, pues <a href=\"https:\/\/latinoamerica21.com\/es\/cuando-una-sentencia-judicial-es-buena-america-latina-en-perspectiva-comparada\/\" target=\"_blank\" rel=\"noreferrer noopener\">sus acciones y decisiones influyen decisivamente en el sistema pol\u00edtico<\/a>. La sentencia de Montesquieu, \u201clos jueces son la boca por donde habla la ley, seres inanimados que no pueden moderar ni su fuerza ni su rigor\u201d, es una visi\u00f3n equ\u00edvoca, y desafortunadamente muy difundida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las leyes nacen en los Parlamentos y, por lo tanto, son un producto pol\u00edtico con objetivos y fines. Para que las leyes funcionen y para que su aplicaci\u00f3n sea justa, tienen que construirse buscando el bien general, y, aun as\u00ed, pueden ser manipuladas. De ah\u00ed que el papel de los jueces sea fundamental. \u00bfCu\u00e1ndo contribuye la actuaci\u00f3n de los jueces al mejoramiento de la democracia? La respuesta es: cuando leg\u00edtimamente hacen valer el Estado de derecho.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En diciembre de 2022 un tribunal penal de Argentina conden\u00f3 a Cristina Fern\u00e1ndez, vicepresidenta y l\u00edder del grupo actual en el poder, a seis a\u00f1os de prisi\u00f3n por corrupci\u00f3n durante sus dos gobiernos. Durante el proceso y, a pesar de las pruebas en su contra, Fern\u00e1ndez nunca dej\u00f3 de considerarse v\u00edctima de una \u201cmafia judicial\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En Brasil, la operaci\u00f3n Lava Jato llev\u00f3 en 2014 al descubrimiento de una red de lavado de dinero que comprendi\u00f3 a m\u00e1s de cuarenta pol\u00edticos y a funcionarios de Petrobras, la mayor empresa petrolera de ese pa\u00eds. Como consecuencia de la mala aplicaci\u00f3n de las leyes y de las presiones indebidas hacia los jueces, pero tambi\u00e9n de la corrupci\u00f3n de algunos de ellos, el caso se politiz\u00f3 hasta el punto de encarcelar al ahora y otra vez presidente Luis Ign\u00e1cio Lula da Silva. En 2019 la sentencia fue revocada y el caso Lava Jato<em> <\/em>qued\u00f3 en entredicho.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Partiendo de las investigaciones a Odebrecht, empresa constructora brasile\u00f1a que sobornaba para ganar contratos de obra p\u00fablica, se juzg\u00f3 y encarcel\u00f3 a pol\u00edticos y a funcionarios de varios niveles de, entre otros pa\u00edses, Brasil, Argentina, Colombia, Per\u00fa y Venezuela.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero las situaciones var\u00edan de pa\u00eds en pa\u00eds. En casos como Per\u00fa, donde entre las personas investigadas est\u00e1n los expresidentes Alejandro Toledo, Alan Garc\u00eda, Ollanta Humala y Pablo Kuczynski, la justicia ha sido contundente y ha enjuiciado a pol\u00edticos de todas las orientaciones pol\u00edticas. Mientras tanto, en M\u00e9xico, Emilio Lozoya, funcionario de alto nivel muy cercano al expresidente Enrique Pe\u00f1a Nieto y con numerosas acusaciones y evidencia de actos il\u00edcitos, goza de libertad condicional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El sistema judicial es un poder de control de otros poderes. Por ello, en Am\u00e9rica Latina los pol\u00edticos, particularmente los presidentes, han tratado de someterlo. La designaci\u00f3n de los m\u00e1s altos cargos judiciales en casi todos los pa\u00edses de la regi\u00f3n es un proceso pol\u00edtico en el que muchas veces cuenta poco la carrera judicial y el prestigio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El reconocimiento del papel pol\u00edtico de los tribunales y las cortes supremas se debe a los procesos de democratizaci\u00f3n que llev\u00f3 a la creaci\u00f3n de nuevas Constituciones o a profundas reformas constitucionales para afirmar derechos pol\u00edticos, sociales, econ\u00f3micos y culturales. No es que antes fueran pasivas y ahora sean activas, sino que la democratizaci\u00f3n ampli\u00f3 su papel como protectora de tales derechos. Sin embargo, cabe destacar que tambi\u00e9n favoreci\u00f3 la judicializaci\u00f3n de la pol\u00edtica, ya que la resoluci\u00f3n de asuntos, que antes se decid\u00edan en la arena pol\u00edtica, ahora se resuelven por la v\u00eda judicial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Judicial es un poder que no obtiene su legitimidad de las urnas, la ciudadan\u00eda acepta las decisiones judiciales porque conf\u00eda en que los jueces cumplen los requisitos que marca la ley y que su formaci\u00f3n y desempe\u00f1o aseguran que tales decisiones se apegan a los principios de derecho y est\u00e1n orientadas hacia la b\u00fasqueda de la justicia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En casi cualquier pa\u00eds, si se descubre que un m\u00e9dico hizo trampa para obtener su grado, inmediatamente se le retira de su funci\u00f3n, independientemente de su historial. \u00bfPor qu\u00e9 no puede suceder lo mismo con un abogado?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La ministra Esquivel obtuvo su t\u00edtulo, consciente de que estaba cometiendo un fraude. Ahora, al permanecer en el cargo, pone en riesgo la legitimidad de la SCJN y de todo el andamiaje del sistema judicial mexicano. Cualquier decisi\u00f3n de la corte sobre casos similares a los mencionados anteriormente, que comprenda temas socialmente delicados y pol\u00edticamente relevantes, estar\u00e1 cubierta por un velo de sospecha antes de siquiera conocerse el veredicto. La SCJN ya no tendr\u00e1 el prestigio que deber\u00eda tener, pues sin legitimidad, la legalidad de las decisiones judiciales estar\u00e1 en tela de juicio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El reconocimiento del papel pol\u00edtico de los tribunales y las cortes supremas se debe a los procesos de democratizaci\u00f3n que llev\u00f3 a profundas reformas constitucionales para afirmar derechos pol\u00edticos, sociales, econ\u00f3micos y culturales. <\/p>\n","protected":false},"author":188,"featured_media":14750,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"episode_type":"","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","footnotes":""},"categories":[17041,16466,16642,16468,16872,16729],"tags":[],"gps":[],"class_list":["post-14749","post","type-post","status-publish","format-standard","has-post-thumbnail","category-sistema-judicial-en","category-mexico","category-sistema-judicial","category-politica","category-mexico-en","category-politica-en"],"acf":[],"_links":{"self":[{"href":"https:\/\/latinoamerica21.com\/es\/wp-json\/wp\/v2\/posts\/14749","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/latinoamerica21.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/latinoamerica21.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/latinoamerica21.com\/es\/wp-json\/wp\/v2\/users\/188"}],"replies":[{"embeddable":true,"href":"https:\/\/latinoamerica21.com\/es\/wp-json\/wp\/v2\/comments?post=14749"}],"version-history":[{"count":0,"href":"https:\/\/latinoamerica21.com\/es\/wp-json\/wp\/v2\/posts\/14749\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/latinoamerica21.com\/es\/wp-json\/wp\/v2\/media\/14750"}],"wp:attachment":[{"href":"https:\/\/latinoamerica21.com\/es\/wp-json\/wp\/v2\/media?parent=14749"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/latinoamerica21.com\/es\/wp-json\/wp\/v2\/categories?post=14749"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/latinoamerica21.com\/es\/wp-json\/wp\/v2\/tags?post=14749"},{"taxonomy":"gps","embeddable":true,"href":"https:\/\/latinoamerica21.com\/es\/wp-json\/wp\/v2\/gps?post=14749"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}