{"id":1692,"date":"2020-05-06T08:08:09","date_gmt":"2020-05-06T11:08:09","guid":{"rendered":"http:\/\/latinoamerica21.com\/?p=1692"},"modified":"2024-06-21T08:01:28","modified_gmt":"2024-06-21T11:01:28","slug":"alemania-enfrenta-la-pandemia-con-una-politica-consensuada-asesoramiento-cientifico-y-responsabilidad-social","status":"publish","type":"post","link":"https:\/\/latinoamerica21.com\/es\/alemania-enfrenta-la-pandemia-con-una-politica-consensuada-asesoramiento-cientifico-y-responsabilidad-social\/","title":{"rendered":"Respuestas a la pandemia: la experiencia de Alemania"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">En una comparaci\u00f3n internacional, parece que Alemania enfrenta bien y con \u00e9xito la pandemia de la COVID-19. Hay muchos menos muertos por el coronavirus que en Italia, Espa\u00f1a, Gran Breta\u00f1a o Francia, y existe un consenso b\u00e1sico, tanto en la clase pol\u00edtica como en la ciudadan\u00eda, de c\u00f3mo enfrentar la crisis. A veces, incluso a Alemania se le atribuye ser un modelo por imitar. &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El balance de Alemania sorprende. En 2019, la Universidad Johns Hopkins public\u00f3 por primera vez el \u00cdndice Global de Seguridad Sanitaria que clasifica los Estados seg\u00fan su capacidad de respuesta a una epidemia o pandemia. En este \u00edndice, Estados Unidos y Gran Breta\u00f1a estaban en las posiciones uno y dos, respectivamente, como los pa\u00edses mejor preparados. A Alemania solo se le atribuy\u00f3 una calificaci\u00f3n regular y qued\u00f3 en la posici\u00f3n 14, solo por delante de Espa\u00f1a (15), Brasil (22), Argentina (25) y Chile (27). <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es posible que el \u00edndice haya sido mal creado. Sin embargo, tambi\u00e9n es probable que la capacidad de los sistemas de salud para responder a una pandemia solo se puedan probar en la pr\u00e1ctica. Por fin, el sector sanitario es parte del sistema pol\u00edtico y social m\u00e1s amplio. La mejor preparaci\u00f3n hipot\u00e9tica para una pandemia no sirve de nada si el liderazgo pol\u00edtico falla o el trabajo de los expertos es torpedeado por pol\u00edticos ineptos o demag\u00f3gicos.&nbsp;&nbsp;&nbsp; &nbsp;&nbsp;<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">En Alemania, se han respetado las opiniones de los expertos y cient\u00edficos, y los epidemi\u00f3logos y vir\u00f3logos se han convertido en estrellas de la televisi\u00f3n\u00bb<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Parafraseando a Bill Clinton, se puede decir que \u00a1es la pol\u00edtica, est\u00fapido! En Alemania, se han respetado las opiniones de los expertos y cient\u00edficos, y los epidemi\u00f3logos y vir\u00f3logos se han convertido en estrellas de la televisi\u00f3n, pues el Gobierno ha basado sus decisiones en sus recomendaciones. Esto retrasa a veces el proceso de tomar decisiones hasta que los resultados cient\u00edficamente probados est\u00e9n disponibles, pero tambi\u00e9n evita decisiones equivocadas. Es la hora de los pol\u00edticos pragm\u00e1ticos y no de los ide\u00f3logos y populistas que, adem\u00e1s, dividen el pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el pasado, el estilo de gobierno pragm\u00e1tico y de construcci\u00f3n de consensos de la canciller \u00c1ngela Merkel ha sido criticado algunas veces, pero ha dado un buen resultado en la situaci\u00f3n actual. La crisis ha demostrado la ventaja que representa que Alemania sea una democracia consensuada. La estrategia de c\u00f3mo enfrentar la pandemia se ha basado en un amplio consenso pol\u00edtico. Con matices, fue apoyado por liberales, dem\u00f3cratas cristianos, la socialdemocracia, los verdes y la izquierda. La extrema <a href=\"https:\/\/latinoamerica21.com\/podcast\/liderazgos-de-derecha-en-america-latina\/\">derecha<\/a> no ha desempe\u00f1ado ning\u00fan papel en la crisis y ha perdido apoyo, seg\u00fan las \u00faltimas encuestas de opini\u00f3n p\u00fablica. No fue la hora de los partidos antisistema y de protesta, sin embargo, ahora est\u00e1n optando por beneficiarse de la crisis econ\u00f3mica e intentan movilizar contra las restricciones econ\u00f3micas a\u00fan existentes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alemania combina un sistema multipartidista con un sistema federal. Como resultado, las coaliciones suelen ser necesarias para formar un Gobierno tanto a escala nacional como a escala de estados federados. Dependiendo del estado, las coaliciones se componen de manera diferente, y esta poligamia pol\u00edtica contrarresta la polarizaci\u00f3n: un contrincante pol\u00edtico en un estado puede ser un socio de coalici\u00f3n en otro. Adem\u00e1s, para la aprobaci\u00f3n de muchas leyes, la C\u00e1mara Alta (o Bundesrat), que est\u00e1 compuesta por representantes de los Gobiernos estatales, tiene que formar mayor\u00edas y dar su consentimiento, lo cual aumenta la presi\u00f3n para forjar un consenso amplio. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por eso, el federalismo alem\u00e1n ha probado su eficacia ante la crisis. Las decisiones m\u00e1s importantes para combatir la pandemia se han tomado de manera coordinada entre el Gobierno federal y los Gobiernos de los estados. Muchas medidas, o su implementaci\u00f3n, son competencia de los estados federales. No obstante, se ha acordado un marco com\u00fan con medidas concertadas que, a la vez, admite una cierta flexibilidad en su ejecuci\u00f3n para tomar en cuenta condiciones locales. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los partidos pol\u00edticos tambi\u00e9n han ejercido un papel importante en la gesti\u00f3n de la crisis del coronavirus. En un principio, fue importante el apoyo de una estrategia com\u00fan por parte de los partidos para combatir la propagaci\u00f3n del virus. Sin embargo, a medida que han aumentado las voces que tienen posiciones divergentes con respecto al alcance de las restricciones, as\u00ed como su duraci\u00f3n, los partidos pol\u00edticos han recogido el debate y, en numerosas ocasiones, con opiniones distintas dentro del mismo partido. Ellos est\u00e1n cumpliendo con su papel de articular, agregar y procesar intereses divergentes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alemania tiene fuertes sindicatos y un sector empresarial bien organizado. Como interlocutores del Gobierno, ambos actores est\u00e1n ayudando al pa\u00eds a paliar la crisis. El estado del bienestar y la econom\u00eda social de mercado que caracteriza a Alemania han&nbsp; demostrado su valor en la crisis. El Gobierno ha adoptado una amplia gama de medidas econ\u00f3micas para conservar los empleos y limitar las p\u00e9rdidas de ingresos. Estas medidas han sido vitales para mantener la paz social y facilitar la aceptaci\u00f3n de las restricciones, a fin de contener el avance de la <a href=\"https:\/\/www.cidob.org\/biografias_lideres_politicos\/organismos\/union_europea\/covid_19_la_respuesta_de_europa_contra_la_pandemia_2020\">pandemia<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ahora estamos entrando en la dif\u00edcil fase de levantar las restricciones y prevenir un nuevo brote para despu\u00e9s comenzar el proceso espinoso de recuperaci\u00f3n econ\u00f3mica. Los Gobiernos han proporcionado mucho dinero para hacer frente a la crisis. Pero \u00bfqui\u00e9n va a pagar la factura al final? \u00bfC\u00f3mo se pueden conciliar las necesidades de una r\u00e1pida recuperaci\u00f3n econ\u00f3mica con las demandas de una reestructuraci\u00f3n ecol\u00f3gica de la econom\u00eda? La econom\u00eda alemana se ha beneficiado de la globalizaci\u00f3n, y su prosperidad depende, en gran medida, de las exportaciones. Otra gran pregunta es: \u00bfqu\u00e9 tipo de globalizaci\u00f3n tendremos despu\u00e9s de la crisis? \u00bfC\u00f3mo se desarrollar\u00e1n los flujos comerciales? Quiz\u00e1s los mayores desaf\u00edos para Alemania est\u00e1n por venir.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Foto en Foter.com<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En una comparaci\u00f3n internacional, parece que Alemania enfrenta bien y con \u00e9xito la pandemia de la COVID-19. Hay muchos menos muertos por el coronavirus que en Italia, Espa\u00f1a, Gran Breta\u00f1a o Francia, y existe un consenso b\u00e1sico, tanto en la clase pol\u00edtica como en la ciudadan\u00eda, de como afrontar la crisis. <\/p>\n","protected":false},"author":70,"featured_media":1693,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"episode_type":"","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","footnotes":""},"categories":[17056,16544,16548,16821,16822,16827,16542],"tags":[],"gps":[],"class_list":["post-1692","post","type-post","status-publish","format-standard","has-post-thumbnail","category-europa-en","category-covid-19-es","category-pandemia","category-coronavirus-en","category-pandemia-en","category-covid-19-es-en","category-coronavirus"],"acf":[],"_links":{"self":[{"href":"https:\/\/latinoamerica21.com\/es\/wp-json\/wp\/v2\/posts\/1692","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/latinoamerica21.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/latinoamerica21.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/latinoamerica21.com\/es\/wp-json\/wp\/v2\/users\/70"}],"replies":[{"embeddable":true,"href":"https:\/\/latinoamerica21.com\/es\/wp-json\/wp\/v2\/comments?post=1692"}],"version-history":[{"count":0,"href":"https:\/\/latinoamerica21.com\/es\/wp-json\/wp\/v2\/posts\/1692\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/latinoamerica21.com\/es\/wp-json\/wp\/v2\/media\/1693"}],"wp:attachment":[{"href":"https:\/\/latinoamerica21.com\/es\/wp-json\/wp\/v2\/media?parent=1692"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/latinoamerica21.com\/es\/wp-json\/wp\/v2\/categories?post=1692"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/latinoamerica21.com\/es\/wp-json\/wp\/v2\/tags?post=1692"},{"taxonomy":"gps","embeddable":true,"href":"https:\/\/latinoamerica21.com\/es\/wp-json\/wp\/v2\/gps?post=1692"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}