{"id":5529,"date":"2021-05-17T08:45:00","date_gmt":"2021-05-17T11:45:00","guid":{"rendered":"http:\/\/latinoamerica21.com\/?p=5529"},"modified":"2021-07-29T05:03:18","modified_gmt":"2021-07-29T08:03:18","slug":"la-gestion-del-miedo-en-la-politica","status":"publish","type":"post","link":"https:\/\/latinoamerica21.com\/es\/la-gestion-del-miedo-en-la-politica\/","title":{"rendered":"La gesti\u00f3n del miedo en la pol\u00edtica"},"content":{"rendered":"\n<p>El miedo es uno de los principales sentimientos que embarga a las personas. La historia de la humanidad no se entiende sin su presencia, tanto en el fuero \u00edntimo de los individuos como en sus relaciones grupales. En el primero se configura como el armaz\u00f3n que sustenta las diferentes religiones o las distintas formas de confrontar la propia existencia; a trav\u00e9s de las segundas articula la convivencia humana, desde las formas sociales m\u00e1s simples a las m\u00e1s complejas, desde la tribu hasta el estado.<\/p>\n\n\n\n<p>Hist\u00f3ricamente, guerras, revoluciones y pandemias han sido caldo de cultivo del miedo, de manera que en ellas ha medrado convirti\u00e9ndose en un actor tan relevante que a veces ha resultado definitivo. En un tono e intensidad disparejas, se hace tambi\u00e9n presente en la convivencia cotidiana de cada \u00e9poca mediante pautas ligadas a variadas expresiones de la injusticia, como la inseguridad y la desigualdad.<\/p>\n\n\n\n<p><strong> Totalitarismos y democracias lo tienen en cuenta para gobernar<\/strong><\/p>\n\n\n\n<p>Por todo ello, dentro de los recursos de los que goza la autoridad, en su m\u00e1xima expresi\u00f3n radica la gesti\u00f3n del miedo. A trav\u00e9s de su administraci\u00f3n se puede legitimar desde el total abuso del poder hasta el logro de un clima social basado en la serena cooperaci\u00f3n entre la gente. Tanto el totalitarismo como la democracia gobiernan teni\u00e9ndolo en cuenta y, aunque obviamente sus supuestos sean diametralmente diferentes, el devenir de ambos, en gran medida, se encuentra muy ligado a \u00e9l.<\/p>\n\n\n\n<p>Con relaci\u00f3n a este asunto, la pandemia de la COVID-19 est\u00e1 resultando un excelente banco de pruebas para evidenciar el estado de las cosas en Am\u00e9rica Latina. Quince meses despu\u00e9s de su irrupci\u00f3n en una regi\u00f3n donde el miedo circula entreverado por los efectos de la exclusi\u00f3n, principal y prevaleciente forma de desigualdad, y ciertas formas de violencia \u00bfc\u00f3mo pueden afectar las medidas de prevenci\u00f3n dictadas por las autoridades en un escenario en el que salir de casa a la calle, cada d\u00eda, es vital para la supervivencia?<\/p>\n\n\n\n<figure class=\"wp-block-pullquote alignright has-background is-style-solid-color\" style=\"background-color:#f2f2f2\"><blockquote class=\"has-text-color has-black-color\"><p>Tambi\u00e9n te podr\u00eda interesar: <a href=\"http:\/\/latinoamerica21.com\/es\/guayaquil-la-imagen-de-la-tragedia\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong><em>Guayaquil, la imagen de la tragedia<\/em><\/strong><\/a><\/p><\/blockquote><\/figure>\n\n\n\n<p>Las escenas con filas de enfermos en los pasillos y entradas de los hospitales o con cad\u00e1veres en las calles, como fue el caso de Guayaquil, provocaron un p\u00e1nico que se traslad\u00f3 al uso masivo de cubrebocas y al imperio de la sanci\u00f3n a quien no los portara. Despu\u00e9s, la implementaci\u00f3n de diferentes formas de excepcionalidad, como los estados de sitio o de alarma, recordaron la m\u00e1xima de Carl Schmitt sobre la definici\u00f3n del soberano. Las poblaciones ventearon las diferentes medidas seg\u00fan el pa\u00eds, pero tambi\u00e9n conforme a su situaci\u00f3n personal de acuerdo con sesgos econ\u00f3micos, sociales o culturales. Desde quienes aceptan todo lo establecido por el poder hasta quienes \u201chacen de su capa un sayo\u201d, la casu\u00edstica es multicolor.<\/p>\n\n\n\n<p><strong>El miedo nutre los discursos oficiales<\/strong><\/p>\n\n\n\n<p>A la par, el miedo ha nutrido una amplia gama de discursos oficiales: algunos obsesivamente presentes, como es el caso, ins\u00f3lito en t\u00e9rminos hist\u00f3ricos, del colombiano Iv\u00e1n Duque dirigi\u00e9ndose diariamente durante una hora a su pa\u00eds; otros, acompa\u00f1ados de decisiones pol\u00edticas m\u00e1s o menos acertadas, van desde <a href=\"http:\/\/latinoamerica21.com\/es\/la-politica-de-muerte-de-bolsonaro\/\" target=\"_blank\" rel=\"noreferrer noopener\">el negacionismo de Jair Bolsonaro en Brasil <\/a>o del mexicano Andr\u00e9s Manuel L\u00f3pez Obrador en el inicio, hasta el m\u00e1s obsesivo de los protocolos de prevenci\u00f3n que ha caracterizado al liberalismo responsable del uruguayo Luis Alberto Lacalle Pou o la actuaci\u00f3n en Costa Rica de Carlos Alvarado, pasando por la m\u00e1s pura y simple inhibici\u00f3n de quienes miran para otro lado, como Alejandro Giammattei en Guatemala, Daniel Ortega en Nicaragua o Abdo Ben\u00edtez en Paraguay.<\/p>\n\n\n\n<p>Todo esto se ha dado en un marco de datos poco fiables e inconsistentes en gran medida, en ocasiones fruto de una debilidad de las instituciones encargadas de su captura (Honduras o El Salvador pueden ser dos casos paradigm\u00e1ticos) y, en otras, de una vesania oficialista (Venezuela y Nicaragua son los dos pa\u00edses m\u00e1s sobresalientes) que contrastan con la eficiencia chilena, quiz\u00e1 por el protagonismo que desde el principio de la pandemia ha tenido su Colegio de M\u00e9dicos. En todo caso, la citada ausencia de un patr\u00f3n de comportamiento \u00fanico, que no es solo patrimonio latinoamericano, ha permitido el surgimiento de varios trabajos e informes sobre el estado de la cuesti\u00f3n, por lo que el grado de conocimiento que se tiene ahora de la situaci\u00f3n es notable.<\/p>\n\n\n\n<p>Ahora bien, entre los dos escenarios opuestos que podr\u00edan resultar, esto es, el de un gobierno azuzando el miedo pand\u00e9mico como mecanismo de control y legitimaci\u00f3n frente a otro negacionista o de negligente actuaci\u00f3n, la regi\u00f3n transita por el filo de ambos. Pol\u00edticamente hablando, el asunto apenas si ha sobrevolado en los comicios celebrados en el \u00faltimo mes en tres pa\u00edses andinos (Bolivia, Ecuador y Per\u00fa) y tampoco enmarca las campa\u00f1as electorales chilena y mexicana, ni la segunda vuelta peruana. Es cierto que ninguno de los responsables m\u00e1ximos de la conducci\u00f3n pol\u00edtica se ha visto o se va a ver sometido a su validaci\u00f3n, por cuanto que o no son objeto de reelecci\u00f3n o no concurren directamente a los comicios, pero la cuesti\u00f3n no aparece de forma preeminente.<\/p>\n\n\n\n<p>Faltos de encuestas de opini\u00f3n p\u00fablica generales para todos los pa\u00edses que puedan se\u00f1alar pautas de comportamiento comparados, los efectos del miedo quedan as\u00ed diluidos o, mejor, configuran apenas una hip\u00f3tesis. Suponen un insumo que, aparentemente, se ci\u00f1e al estricto nivel individual en cuanto alteraci\u00f3n, o no, de las expectativas vitales de cada persona.<\/p>\n\n\n\n<p>Adem\u00e1s, si se tiene en cuenta que toda pandemia, como se\u00f1ala el padre de la anatom\u00eda patol\u00f3gica, Rudolf Virchow, es \u201cun fen\u00f3meno social que conlleva algunos aspectos m\u00e9dicos\u201d, cabr\u00eda preguntarse por su impacto en sociedades l\u00edquidas profundamente desiguales y empobrecidas, donde la transici\u00f3n digital genera, a su vez, todo tipo de dilemas y m\u00e1s brechas.<\/p>\n\n\n\n<p>Por todo ello, el riesgo es que su gesti\u00f3n termine siendo profundamente disruptiva en niveles muy fragmentados que pueden tener un enorme impacto en democracias fatigadas cuyo futuro es m\u00e1s incierto que hace apenas un lustro. El salto de una pol\u00edtica del miedo a una pol\u00edtica del cuidado, <a href=\"https:\/\/www.lavoz.com.ar\/numero-cero\/de-butler-a-chul-han-mundo-que-nos-espera\/\" target=\"_blank\" rel=\"noreferrer noopener\">como se\u00f1alan Franco Berardi y Byung Chul Han<\/a>, es un imperativo ante el que, a d\u00eda de hoy, pocos reaccionan.<\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<p class=\"has-text-align-right\"><strong><em>Episodio relacionado de nuestro\u00a0<a href=\"http:\/\/latinoamerica21.com\/podcast\/\">podcast<\/a><\/em><\/strong>:<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-spotify wp-block-embed-spotify wp-embed-aspect-21-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Spotify Embed: Crisis de la democracia en Latinoam\u00e9rica\" style=\"border-radius: 12px\" width=\"100%\" height=\"152\" frameborder=\"0\" allowfullscreen allow=\"autoplay; clipboard-write; encrypted-media; fullscreen; picture-in-picture\" loading=\"lazy\" src=\"https:\/\/open.spotify.com\/embed\/episode\/3XBfbiL2vbQuBv8hsX3iGD?si=cu-pvqggSLWPRnORxPODrQ&#038;utm_source=oembed\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<p><em><sub>Foto de Esparta en Foter.com y Foto de manolo guijarro en Foter.com<\/sub><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El miedo es uno de los principales sentimientos que embarga a las personas. La historia de la humanidad no se entiende sin su presencia ya que articula la convivencia humana, desde las formas sociales m\u00e1s simples a las m\u00e1s complejas, desde la tribu hasta el estado.<\/p>\n","protected":false},"author":45,"featured_media":5531,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"episode_type":"","audio_file":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","footnotes":""},"categories":[17039],"tags":[],"gps":[],"class_list":{"0":"post-5529","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-internet-es-en"},"acf":[],"_links":{"self":[{"href":"https:\/\/latinoamerica21.com\/es\/wp-json\/wp\/v2\/posts\/5529","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/latinoamerica21.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/latinoamerica21.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/latinoamerica21.com\/es\/wp-json\/wp\/v2\/users\/45"}],"replies":[{"embeddable":true,"href":"https:\/\/latinoamerica21.com\/es\/wp-json\/wp\/v2\/comments?post=5529"}],"version-history":[{"count":0,"href":"https:\/\/latinoamerica21.com\/es\/wp-json\/wp\/v2\/posts\/5529\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/latinoamerica21.com\/es\/wp-json\/wp\/v2\/media\/5531"}],"wp:attachment":[{"href":"https:\/\/latinoamerica21.com\/es\/wp-json\/wp\/v2\/media?parent=5529"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/latinoamerica21.com\/es\/wp-json\/wp\/v2\/categories?post=5529"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/latinoamerica21.com\/es\/wp-json\/wp\/v2\/tags?post=5529"},{"taxonomy":"gps","embeddable":true,"href":"https:\/\/latinoamerica21.com\/es\/wp-json\/wp\/v2\/gps?post=5529"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}