{"id":56403,"date":"2026-05-13T09:00:00","date_gmt":"2026-05-13T12:00:00","guid":{"rendered":"https:\/\/latinoamerica21.com\/?p=56403"},"modified":"2026-05-12T12:55:30","modified_gmt":"2026-05-12T15:55:30","slug":"o-caribe-como-tabuleiro-dos-estados-unidos","status":"publish","type":"post","link":"https:\/\/latinoamerica21.com\/pt-br\/o-caribe-como-tabuleiro-dos-estados-unidos\/","title":{"rendered":"O Caribe como tabuleiro dos Estados Unidos"},"content":{"rendered":"\n<p>O mapa da Grande Am\u00e9rica do Norte anunciado pelo secret\u00e1rio de Guerra dos Estados Unidos, Pete Hegseth, delimita a nova zona de influ\u00eancia estrat\u00e9gica de Washington. Seu desenho remete inevitavelmente \u00e0 Doutrina Monroe de 1823, quando os estadunidenses concebiam como seu espa\u00e7o vital o M\u00e9xico, a Am\u00e9rica Central, o Caribe, a Venezuela e parte da Col\u00f4mbia. No entanto, a constru\u00e7\u00e3o de uma hegemonia mar\u00edtima foi interrompida por v\u00e1rios fatores.<\/p>\n\n\n\n<p>Desde o retorno de Trump \u00e0 Casa Branca, Washington intensificou sua presen\u00e7a na regi\u00e3o mediante opera\u00e7\u00f5es militares e aproxima\u00e7\u00f5es com pa\u00edses como Trinidad e Tobago, Barbados e Jamaica, que na \u00e9poca condenaram o governo autorit\u00e1rio de Nicol\u00e1s Maduro. A isso se somou a c\u00fapula Escudo das Am\u00e9ricas, da qual participaram a Rep\u00fablica Dominicana e Trinidad e Tobago para assinar acordos de coopera\u00e7\u00e3o no combate ao crime. Paralelamente, o secret\u00e1rio de Estado, Marco Rubio, refor\u00e7ou o di\u00e1logo com a Comunidade do Caribe (CARICOM).<\/p>\n\n\n\n<p>Rubio recorreu a esse organismo para pedir aos l\u00edderes insulares uma maior coopera\u00e7\u00e3o com Washington, argumentando que, se eles estiverem bem, os Estados Unidos tamb\u00e9m estar\u00e3o. O Caribe tem agora um papel central na constru\u00e7\u00e3o da nova hegemonia que se iniciou com a pris\u00e3o de Maduro e que se mant\u00e9m com as press\u00f5es sobre Cuba. A Casa Branca n\u00e3o quer repetir os erros do passado e agora aspira a consolidar um controle mais firme em sua zona de influ\u00eancia.<\/p>\n\n\n\n<p>At\u00e9 Donald Trump, que se diz admirador do rei Charles III, chefe da <em>Commonwealth<\/em> e chefe de Estado de v\u00e1rias na\u00e7\u00f5es caribenhas, afirmou em 2025 em sua rede Truth Social que achava bom que os Estados Unidos pudessem aderir a essa organiza\u00e7\u00e3o. Jornais como <em>The Times<\/em> e <em>El Mundo<\/em> interpretaram essa proposta como uma forma de fortalecer a influ\u00eancia de Washington no Caribe.<\/p>\n\n\n\n<p><strong>Um olhar para o passado<\/strong><\/p>\n\n\n\n<p>Desde o s\u00e9culo XVIII, a presen\u00e7a das pot\u00eancias coloniais europeias no Caribe era latente. O Reino Unido manteve territ\u00f3rios como Bahamas, S\u00e3o Crist\u00f3v\u00e3o e Nevis, Ant\u00edgua e Barbuda, Jamaica, Barbados, Granada e Dominica, para citar alguns. Por sua vez, a Fran\u00e7a manteve seus Departamentos Ultramarinos em Guadalupe, Martinica e Guiana Francesa, enquanto a Espanha conservou at\u00e9 a guerra de 1898 suas \u00faltimas col\u00f4nias, Porto Rico e Cuba, perdidas para os americanos.<\/p>\n\n\n\n<p>A partir de ent\u00e3o, os Estados Unidos coabitaram no Caribe junto com as pot\u00eancias europeias, embora, ao mesmo tempo, apoiassem governos de car\u00e1ter autorit\u00e1rio que se alinhavam com a Casa Branca. Entre eles destacam-se a ditadura de Rafael Le\u00f3nidas Trujillo na Rep\u00fablica Dominicana, os governos de Fran\u00e7ois e Jean-Claude Duvalier no Haiti e a administra\u00e7\u00e3o de Fulgencio Batista em Cuba antes da Revolu\u00e7\u00e3o Cubana.<\/p>\n\n\n\n<p>A l\u00f3gica de interven\u00e7\u00e3o se manteve durante a Guerra Fria. Em 1965, os dominicanos tentaram reinstaurar Juan Bosch na presid\u00eancia, mas a Casa Branca invadiu o pa\u00eds para impedir isso. Quase vinte anos depois, em 1983, o governo de Ronald Reagan ordenou uma invas\u00e3o a Granada depois que o primeiro-ministro, Hudson Austin, chegou ao poder por meio de um golpe de Estado. Washington argumentou que o novo governo colocava em risco sua seguran\u00e7a e, juntamente com tropas de Barbados e da Jamaica, dep\u00f4s o l\u00edder golpista.<\/p>\n\n\n\n<p>A opera\u00e7\u00e3o gerou mal estar em Londres, pois a ent\u00e3o primeira-ministra, Margaret Thatcher, declarou que o Reino Unido n\u00e3o foi consultado sobre a interven\u00e7\u00e3o em uma na\u00e7\u00e3o pertencente \u00e0 Commonwealth. Dessa forma, e apesar de, inicialmente, sob a Doutrina Monroe, os Estados Unidos terem defendido a expuls\u00e3o de todas as pot\u00eancias europeias do continente, durante a Guerra Fria a Casa Branca aproximou-se dessas na\u00e7\u00f5es e formou com elas uma rela\u00e7\u00e3o estrat\u00e9gica.<\/p>\n\n\n\n<p><strong>O Caribe, uma regi\u00e3o estrat\u00e9gica<\/strong><\/p>\n\n\n\n<p>O Caribe tem sido historicamente uma pe\u00e7a central da hegemonia no hemisf\u00e9rio, n\u00e3o s\u00f3 por ser a porta de entrada para o interc\u00e2mbio comercial com a \u00c1frica e a \u00c1sia, mas tamb\u00e9m por permitir projetar influ\u00eancia na Am\u00e9rica do Sul. Ap\u00f3s a instaura\u00e7\u00e3o do governo socialista liderado por Fidel Castro em Cuba, os Estados Unidos promoveram o isolamento da ilha em rela\u00e7\u00e3o a ilhas como a Jamaica e Trinidad e Tobago, justamente para evitar que esses pa\u00edses adotassem governos de esquerda.<\/p>\n\n\n\n<p>Nesse contexto, o Haiti representa um ponto sens\u00edvel. Mergulhado em uma crise pol\u00edtica, econ\u00f4mica, de sa\u00fade e de seguran\u00e7a desde 2021, o pa\u00eds \u00e9 importante para os Estados Unidos. O Alto Conselho de Transi\u00e7\u00e3o, \u00f3rg\u00e3o que exerce o controle do pa\u00eds devido \u00e0 aus\u00eancia de autoridades eleitas, prev\u00ea a realiza\u00e7\u00e3o de elei\u00e7\u00f5es no pr\u00f3ximo dia 30 de agosto. Embora Trump tenha se referido pouco publicamente ao Haiti, a fragilidade do pa\u00eds o torna um elo vulner\u00e1vel que sofrer\u00e1 press\u00f5es para cumprir os des\u00edgnios de Washington.<\/p>\n\n\n\n<p>Em conclus\u00e3o, o Caribe representa hoje um dos pontos geopol\u00edticos mais relevantes para a Casa Branca: \u00e9 a porta de entrada natural para a Am\u00e9rica continental e um corredor fundamental para o interc\u00e2mbio comercial. Sob uma nova Doutrina Monroe, Washington busca unir todas as pe\u00e7as do quebra-cabe\u00e7a para consolidar uma hegemonia hemisf\u00e9rica que, durante os anos 90, foi negligenciada.<\/p>\n\n\n\n<p><em><sub>Tradu\u00e7\u00e3o autom\u00e1tica revisada por Isabel Lima<\/sub><\/em><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O renovado ativismo de Washington na regi\u00e3o reaviva a l\u00f3gica da Doutrina Monroe e reposiciona o Caribe como eixo estrat\u00e9gico de sua influ\u00eancia hemisf\u00e9rica.<\/p>\n","protected":false},"author":404,"featured_media":56399,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"episode_type":"","audio_file":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","footnotes":""},"categories":[16762],"tags":[15839],"gps":[],"class_list":{"0":"post-56403","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-relaiciones-internacionales-pt-br","8":"tag-ideias-pt-br"},"acf":[],"_links":{"self":[{"href":"https:\/\/latinoamerica21.com\/pt-br\/wp-json\/wp\/v2\/posts\/56403","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/latinoamerica21.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/latinoamerica21.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/latinoamerica21.com\/pt-br\/wp-json\/wp\/v2\/users\/404"}],"replies":[{"embeddable":true,"href":"https:\/\/latinoamerica21.com\/pt-br\/wp-json\/wp\/v2\/comments?post=56403"}],"version-history":[{"count":1,"href":"https:\/\/latinoamerica21.com\/pt-br\/wp-json\/wp\/v2\/posts\/56403\/revisions"}],"predecessor-version":[{"id":56404,"href":"https:\/\/latinoamerica21.com\/pt-br\/wp-json\/wp\/v2\/posts\/56403\/revisions\/56404"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/latinoamerica21.com\/pt-br\/wp-json\/wp\/v2\/media\/56399"}],"wp:attachment":[{"href":"https:\/\/latinoamerica21.com\/pt-br\/wp-json\/wp\/v2\/media?parent=56403"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/latinoamerica21.com\/pt-br\/wp-json\/wp\/v2\/categories?post=56403"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/latinoamerica21.com\/pt-br\/wp-json\/wp\/v2\/tags?post=56403"},{"taxonomy":"gps","embeddable":true,"href":"https:\/\/latinoamerica21.com\/pt-br\/wp-json\/wp\/v2\/gps?post=56403"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}